{"id":3813,"date":"2014-10-07T20:43:15","date_gmt":"2014-10-07T17:43:15","guid":{"rendered":"http:\/\/jedi-kids.ro\/?p=25"},"modified":"2016-11-03T18:27:00","modified_gmt":"2016-11-03T18:27:00","slug":"joaca-cu-bebelusii","status":"publish","type":"post","link":"https:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/","title":{"rendered":"Joaca cu bebelusii"},"content":{"rendered":"<p>Tocmai am vizitat noul nostru nepotel. Ajung acasa incantata cu pozele bebelusului.<br \/>\n<strong>Mama:<\/strong> Luke, vino sa-l vezi pe noul tau verisor, uite ce mic este! Cand vrei sa mergem sa te joci cu el?<br \/>\nLuke vine sa vada pozele, se uita la ele&#8230; si zice:<br \/>\n&#8211; Hmmm &#8230; cred ca peste cativa ani!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tocmai am vizitat noul nostru nepotel. Ajung acasa incantata cu pozele bebelusului. Mama: Luke, vino sa-l vezi pe noul tau verisor, uite ce mic este! Cand vrei sa mergem sa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[42],"class_list":["post-3813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-49","tag-umor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Joaca cu bebelusii - Jedi Kids<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joaca cu bebelusii - Jedi Kids\" \/>\n<meta property=\"og:description\" content=\"Tocmai am vizitat noul nostru nepotel. Ajung acasa incantata cu pozele bebelusului. Mama: Luke, vino sa-l vezi pe noul tau verisor, uite ce mic este! Cand vrei sa mergem sa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/\" \/>\n<meta property=\"og:site_name\" content=\"Jedi Kids\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-07T17:43:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-03T18:27:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ms. N.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/jedikids.ro\/site\/#website\",\"url\":\"http:\/\/jedikids.ro\/site\/\",\"name\":\"Jedi Kids\",\"description\":\"\u00een\u021belepciunea copiilor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/jedikids.ro\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg\",\"contentUrl\":\"https:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg\",\"width\":300,\"height\":200},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#webpage\",\"url\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/\",\"name\":\"Joaca cu bebelusii - Jedi Kids\",\"isPartOf\":{\"@id\":\"http:\/\/jedikids.ro\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#primaryimage\"},\"datePublished\":\"2014-10-07T17:43:15+00:00\",\"dateModified\":\"2016-11-03T18:27:00+00:00\",\"author\":{\"@id\":\"http:\/\/jedikids.ro\/site\/#\/schema\/person\/18cd3b35e8431c381afafe4afa87261d\"},\"breadcrumb\":{\"@id\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/jedikids.ro\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joaca cu bebelusii\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/jedikids.ro\/site\/#\/schema\/person\/18cd3b35e8431c381afafe4afa87261d\",\"name\":\"Ms. N.\",\"url\":\"https:\/\/jedikids.ro\/site\/ro\/author\/mama\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joaca cu bebelusii - Jedi Kids","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/","og_locale":"en_US","og_type":"article","og_title":"Joaca cu bebelusii - Jedi Kids","og_description":"Tocmai am vizitat noul nostru nepotel. Ajung acasa incantata cu pozele bebelusului. Mama: Luke, vino sa-l vezi pe noul tau verisor, uite ce mic este! Cand vrei sa mergem sa [&hellip;]","og_url":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/","og_site_name":"Jedi Kids","article_published_time":"2014-10-07T17:43:15+00:00","article_modified_time":"2016-11-03T18:27:00+00:00","og_image":[{"width":300,"height":200,"url":"http:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Written by":"Ms. N."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/jedikids.ro\/site\/#website","url":"http:\/\/jedikids.ro\/site\/","name":"Jedi Kids","description":"\u00een\u021belepciunea copiilor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jedikids.ro\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#primaryimage","inLanguage":"en-US","url":"https:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg","contentUrl":"https:\/\/jedikids.ro\/site\/wp-content\/uploads\/2014\/10\/bebe.jpeg","width":300,"height":200},{"@type":"WebPage","@id":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#webpage","url":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/","name":"Joaca cu bebelusii - Jedi Kids","isPartOf":{"@id":"http:\/\/jedikids.ro\/site\/#website"},"primaryImageOfPage":{"@id":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#primaryimage"},"datePublished":"2014-10-07T17:43:15+00:00","dateModified":"2016-11-03T18:27:00+00:00","author":{"@id":"http:\/\/jedikids.ro\/site\/#\/schema\/person\/18cd3b35e8431c381afafe4afa87261d"},"breadcrumb":{"@id":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/jedikids.ro\/site\/ro\/joaca-cu-bebelusii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/jedikids.ro\/site\/"},{"@type":"ListItem","position":2,"name":"Joaca cu bebelusii"}]},{"@type":"Person","@id":"http:\/\/jedikids.ro\/site\/#\/schema\/person\/18cd3b35e8431c381afafe4afa87261d","name":"Ms. N.","url":"https:\/\/jedikids.ro\/site\/ro\/author\/mama\/"}]}},"_links":{"self":[{"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/posts\/3813"}],"collection":[{"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/comments?post=3813"}],"version-history":[{"count":1,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/posts\/3813\/revisions"}],"predecessor-version":[{"id":3818,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/posts\/3813\/revisions\/3818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/media\/3817"}],"wp:attachment":[{"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/media?parent=3813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/categories?post=3813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jedikids.ro\/site\/wp-json\/wp\/v2\/tags?post=3813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}